{"id":3790,"date":"2023-09-20T10:08:43","date_gmt":"2023-09-20T08:08:43","guid":{"rendered":"https:\/\/db-eco.com\/?p=3790"},"modified":"2025-05-07T01:12:19","modified_gmt":"2025-05-06T23:12:19","slug":"herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv","status":"publish","type":"post","link":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/","title":{"rendered":"Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv"},"content":{"rendered":"\n<div class=\"wp-block-dbec-core-layout-grid  layout-grid layout-grid--outer-margin-large layout-grid--expanded\"><div class=\"grid grid--child-margin-large\">\n<div class=\"wp-block-dbec-core-layout-column  column is-6-small is-6-medium column--expanded\"><div class=\"layout-column\"><nav class=\"breadcrumbs\"><div class=\"breadcrumbs__inner\"><a class=\"breadcrumbs__home\" href=\"https:\/\/db-eco.com\/de\/\" aria-label=\"Link Home\"><svg class=\"breadcrumbs__home-icon\"><use xlink:href=\"#home\"><\/use><\/svg><\/a> <svg class=\"breadcrumbs__delimiter\"><use xlink:href=\"#icon-arrow-right\"><\/use><\/svg> <a data-is-distributor=\"true\" href=\"https:\/\/db-eco.com\/de\/aktuelles\/\">Aktuelles<\/a> <svg class=\"breadcrumbs__delimiter\"><use xlink:href=\"#icon-arrow-right\"><\/use><\/svg><span class=\"breadcrumbs__actual-page\">Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv<\/span><\/div><\/nav><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-dbec-core-layout-grid  layout-grid layout-grid--outer-margin-small layout-grid--expanded\"><div class=\"grid grid--child-margin-small\">\n<div class=\"wp-block-dbec-core-layout-column  column is-6-small is-3-medium column--expanded\"><div class=\"layout-column\">\n<div class=\"wp-block-dbec-core-layout-text  wp-block-dbec-core-layout-text--expanded\"><div class=\"layout-column layout-column--text\"><div class=\"article-header\"><div class=\"article-header__tags\"><a class=\"tag\" href=\"https:\/\/db-eco.com\/de\/aktuelles\/?categories=1\">News<\/a><a class=\"tag\" href=\"https:\/\/db-eco.com\/de\/aktuelles\/?categories=2\">News<\/a><\/div><h1 class=\"article-header__headline\">Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv<\/h1><div class=\"article-header__date\">20.09.2023 &#8211; 10:08<\/div><\/div>\n\n\n<div class=\"wp-block-dbec-core-sub-headline\"><p class=\"sub-headline\">Um dem wachsenden Mobilit\u00e4tsbedarf der St\u00e4dte gerecht zu werden, wurde f\u00fcr Tel Aviv ein hochmodernes MRT(Mass Rapid Transit)-System entwickelt, das sich durch Effizienz, Geschwindigkeit, Zuverl\u00e4ssigkeit und Umweltfreundlichkeit auszeichnet. Das System umfasst drei geplante Stadtbahnlinien, mit denen die Personenbef\u00f6rderung \u00fcber die Metropolregion hinweg f\u00fcr mehr als vier Millionen Einwohner verbessert wird. Nun hat die erste dieser Linien erfolgreich den Betrieb aufgenommen. <\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-dbec-core-figure\"><figure class=\"figure\"><div class=\"figure__inner\"><img decoding=\"async\" class=\"figure__image\" src=\"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg\" srcset=\"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-300x200.jpg 300w, https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-150x150.jpg 150w, https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-768x511.jpg 768w, https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-520x346.jpg 520w, https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-768x511.jpg 768w\" alt=\"Stadtbahn Tel Aviv w\u00e4hrend der Fahrt durch die Stadt\" width=\"775\" height=\"516\" loading=\"lazy\" sizes=\"auto, (min-width: 1330px) calc(((1200px - 35px * 5) * (3 \/ 6)) + (35px * (3 - 1))), (min-width: 768px) calc((((100vw - 130px) - 35px * 5) * (3 \/ 6)) + (35px * (3 - 1))), calc(100vw - 60px)\"\/><div class=\"label-reference\" data-image-reference=\"<p&gt;Marco Cigolini \/ DB Engineering &#038; Consulting<\/p&gt;\n\"><\/div><\/div><\/figure><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-dbec-core-layout-column  column is-6-small is-2-medium is-offset-left-1-medium column--expanded\"><div class=\"layout-column\">\n<div class=\"wp-block-dbec-core-layout-text  wp-block-dbec-core-layout-text--expanded\"><div class=\"layout-column layout-column--text\"><div class=\"wp-block-dbec-core-social-sharing\"><div class=\"social-sharing\" data-subject=\"\" data-recipient=\"\" data-body=\"\"><span class=\"social-sharing__label\">Social Sharing<\/span><div class=\"social-sharing__links\"><a class=\"social-sharing__link social-sharing__link--linkedin\" href=\"\/\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Link LinkedIn\"><svg class=\"social-sharing__icon\"><use xlink:href=\"#icon-linked-in\"\/><\/svg><\/a><a class=\"social-sharing__link social-sharing__link--mail\" href=\"\/\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"Link Mail\"><svg class=\"social-sharing__icon\"><use xlink:href=\"#icon-mail\"\/><\/svg><\/a><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-dbec-core-layout-text  wp-block-dbec-core-layout-text--expanded\"><div class=\"layout-column layout-column--text\">\n<h2 class=\"wp-block-heading headline-h4\">Kontakt<\/h2>\n\n\n<div class=\"contact-person\"><h3 class=\"contact-person__name\">DB E.C.O. Group<\/h3><div class=\"contact-person__position\">Team Marketing &#038; Kommunikation<\/div><div class=\"contact-person__address\">EUREF-Campus 14<br \/>\r\n10829 Berlin<br \/>\r\nDeutschland<\/div><a class=\"contact-person__link-communication\" href=\"mailto:marketing@db-eco.com\"><svg class=\"contact-person__icon-mail\"><use xlink:href=\"#icon-mail\"><\/use><\/svg><span>E-Mail<\/span><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-dbec-core-layout-grid  layout-grid layout-grid--outer-margin-small layout-grid--expanded\"><div class=\"grid grid--child-margin-small\">\n<div class=\"wp-block-dbec-core-layout-column  column is-6-small is-4-medium column--expanded\"><div class=\"layout-column\">\n<p>In einer Stadt wie Tel Aviv, die f\u00fcr ihr konsequentes Innovationsstreben bekannt ist und weltweit einen guten Ruf als Standort von Startups genie\u00dft, ist das hochmoderne Stadtbahnsystem ein klares Bekenntnis zu zukunftsweisender st\u00e4dtischer Mobilit\u00e4t. Mit seinem Schwerpunkt auf Effizienz, Zuverl\u00e4ssigkeit und Nachhaltigkeit wird das Stadtbahnsystem mit seinen drei geplanten Linien die Art und Weise, wie sich die Menschen im Gro\u00dfraum Tel Aviv fortbewegen, mit Sicherheit grundlegend ver\u00e4ndern. Das Herzst\u00fcck dieses Transformationsprojekts ist die Red Line, die einen Gro\u00dfteil ihres Erfolgs dem Beitrag von <a href=\"https:\/\/db-engineering-consulting.com\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">DB Engineering &amp; Consulting (DB E&amp;C)<\/a>, Teil der DB E.C.O. Group, verdankt.<\/p>\n\n\n\n<p>Der von den Einwohnern Tel Avivs mit gro\u00dfer Begeisterung erwartete offizielle Start des Fahrgastbetriebs der Red Line fand am 18. August 2023 statt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading headline-h3\">Effizienz als Vision: das Stadtbahnsystem der Red Line von Tel Aviv<\/h2>\n\n\n\n<p>Da die Anforderungen in den St\u00e4dten immer weiter steigen, kommt einer modernen, effizienten und umweltfreundlichen Transportl\u00f6sung eine immer gr\u00f6\u00dfere Bedeutung zu. Das Stadtbahnsystem der Red Line von Tel Aviv, das diesen Bed\u00fcrfnissen Rechnung tragen soll, wird immer st\u00e4rker zu einem Aush\u00e4ngeschild des Wandels. Dieses Bahnsystem mit hoher Taktfrequenz verspricht eine schnelle, komfortable und sichere Bef\u00f6rderung unter Einhaltung h\u00f6chster Standards in Bezug auf Zuverl\u00e4ssigkeit und P\u00fcnktlichkeit.<\/p>\n\n\n\n<h2 class=\"wp-block-heading headline-h3\">Die wichtige Rolle der DB bei Integration und Absicherung<\/h2>\n\n\n\n<p>Als Unterauftragnehmer des chinesischen Konsortiums CRTG-EEB spielte DB E&amp;C eine entscheidende Rolle bei der nahtlosen Integration und Absicherung des Projekts. Die Komplexit\u00e4t der Red Line, die sowohl ebenerdige als auch unterirdische Abschnitte umfasst, erforderte ein fundiertes Fachwissen, um wichtige Prozesse, wie sie in der Norm EN 50126 (RAMS) festgelegt werden, ordnungsgem\u00e4\u00df zu steuern. Gleiches gilt auch f\u00fcr die \u00dcberwachung von Anforderungsmanagement, Konfigurationsmanagement, Systemintegration, Pr\u00fcfung und Inbetriebnahme, Systemsicherung, Schnittstellenmanagement und Risikomanagement.<\/p>\n\n\n\n<p>Eine der bemerkenswerten Leistungen von DB E&amp;C war die Schl\u00fcsselrolle bei der Erlangung der erforderlichen Genehmigung des unabh\u00e4ngigen Sicherheitsgutachters f\u00fcr das gesamte System. Diese Genehmigung, ein wichtiger aufsichtsrechtlicher Meilenstein, bescheinigt die Compliance des Projekts mit strengen Sicherheitsstandards.<\/p>\n\n\n\n<h2 class=\"wp-block-heading headline-h3\">Pr\u00fcfung der Grenzen: Beitrag zur Pr\u00fcfung und Inbetriebnahme<\/h2>\n\n\n\n<p>Ein wesentlicher Meilenstein in jedem Bef\u00f6rderungsprojekt f\u00e4llt in die <a href=\"https:\/\/db-engineering-consulting.com\/de\/produktportfolio\/pruefung-und-begutachtung\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00fcfungs- und Inbetriebnahmephase<\/a>.&nbsp; DB E&amp;C spielte eine Schl\u00fcsselrolle bei der akribischen Abstimmung eines umfassenden Pr\u00fcfplans, bei dem jede Facette des Stadtbahnsystems der Red Line unter die Lupe genommen wurde.<\/p>\n\n\n\n<p>Die Erarbeitung einer effektiven Pr\u00fcf- und Inbetriebnahmeplanung beruhte auf einer Bottom-up-Strategie zur Systemintegration, bei der die optimalen Parameter f\u00fcr den Prozess ermittelt wurden. Dieser Ansatz stellte sicher, dass sich die erbrachten Leistungen an den komplexen Zusammenh\u00e4ngen der Funktionst\u00fcchtigkeit des Systems orientierten und dem Risiko entsprachen, das aus einer derartigen Systemkomplexit\u00e4t resultiert.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus wurden fortschrittliche Methodiken und Plattformen f\u00fcr eine minuti\u00f6se R\u00fcckverfolgbarkeit und umfassende Dokumentation aller Pr\u00fcf- und Inbetriebnahmeaktivit\u00e4ten eingesetzt. Dadurch wurde nicht nur die Rechenschaftspflicht verbessert, sondern auch die Verfolgung von Fortschritten erleichtert. Zudem konnten dadurch auch Bereiche ermittelt werden, in denen potentielle Verbesserungen m\u00f6glich sind.<\/p>\n\n\n\n<h2 class=\"wp-block-heading headline-h3\">Die Grenzen neu definieren: die einzigartigen Merkmale der Red Line<\/h2>\n\n\n\n<p>Die Einzigartigkeit der Red Line kommt auch in ihrem Design zum Ausdruck. Bemerkenswerte Merkmale wie z. B. Stationen, die im Falle eines Angriffs als explosionsgesch\u00fctzte R\u00e4ume dienen k\u00f6nnen, unterstreichen den sicherheitsorientierten Ansatz des Systems. Mit der Integration eines umfangreichen L\u00fcftungssystems und eines hochmodernen PSIM(Physical Security Information Management)-Systems, das automatisch auf Notf\u00e4lle reagiert, setzt sich dieses Projekt weiter ab.<\/p>\n\n\n\n<p>Dar\u00fcber hinaus verf\u00fcgt die Red Line \u00fcber ein automatisches Zug\u00fcberwachungssystem (ATS) und ein kommunikationsgest\u00fctztes Zugsteuerungssystem (CBTC), das sowohl automatische als auch manuelle Fahrmodi unterst\u00fctzt. Dieser bahnbrechende Ansatz verdeutlicht den Ehrgeiz des Projekts, die Grenzen moderner st\u00e4dtischer Bef\u00f6rderungssysteme weiter hinauszuschieben.<\/p>\n\n\n\n<p>Im Bereich st\u00e4dtischer Bef\u00f6rderungssysteme wurde dieser Ansatz nur bei wenigen anderen Projekten umgesetzt. In New York City wird beispielsweise das System CBTC 2.0 auf mehreren Linien eingef\u00fchrt, um die Kapazit\u00e4t zu erh\u00f6hen, Versp\u00e4tungen zu verringern und die Zuverl\u00e4ssigkeit des Systems durch automatische und manuelle Betriebsarten abzusichern. In \u00e4hnlicher Weise wird bei der Londoner U-Bahn im Rahmen des Projekts &#8220;Four Lines Modernization&#8221; ein CBTC-System eingef\u00fchrt, das durch den Einsatz von automatischen und manuellen Fahrmodi eine verbesserte betriebliche Effizienz erm\u00f6glicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading headline-h3\">H\u00fcrden \u00fcberwinden: nahtlose Integration<\/h2>\n\n\n\n<p>Integrationsprobleme sind bei komplexen Projekten zu erwarten, und die Red Line war da keine Ausnahme. Das Alstom-Signalsystem brachte einzigartige Herausforderungen mit sich, einschlie\u00dflich der Implementierung eines CBTC-Systems auf den ebenerdigen und unterirdischen Abschnitten der Linie. Dies erforderte eine pr\u00e4zise Probleml\u00f6sung zur Optimierung der Software-Konfiguration f\u00fcr die Signalisierung \u00fcber die gesamte Linie. Die Erfahrung von DB E&amp;C auf dem Gebiet der Systemintegration trug entscheidend dazu bei, die technische Fehlersuche zu unterst\u00fctzen. Dadurch konnten Probleme gel\u00f6st werden, die sich auf einige der Systemfunktionen auswirkten, um so die Gesamtbetriebsf\u00e4higkeit des Stadtbahnsystems der Red Line sicherzustellen.<\/p>\n\n\n\n<p>Das <a href=\"https:\/\/db-engineering-consulting.com\/en\/projects\/tel-aviv-metro-light-rail-transit-system-integration\/\" target=\"_blank\" rel=\"noreferrer noopener\">Stadtbahnsystem der Red Line in Tel Aviv<\/a> ist ein Beleg f\u00fcr das Potenzial, das bei der Ausgestaltung der urbanen Mobilit\u00e4t der Zukunft aus Zusammenarbeit, Innovation und Fachwissen resultiert. Die Rolle von DB E&amp;C bei der Sicherstellung von Sicherheit, Integration und betrieblicher Exzellenz dient als Inspiration f\u00fcr st\u00e4dtische Infrastrukturma\u00dfnahmen weltweit. W\u00e4hrend sich die St\u00e4dte weiterentwickeln, ebnen solche Projekte den Weg f\u00fcr smartere Verkehrsnetze mit mehr Sicherheit und Nachhaltigkeit, die das Gemeinwesen st\u00e4rken und den Fortschritt vorantreiben.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-dbec-core-layout-grid  layout-grid layout-grid--outer-margin-large layout-grid--expanded\"><div class=\"grid grid--child-margin-small\">\n<div class=\"wp-block-dbec-core-layout-column  column is-6-small is-6-medium column--expanded\"><div class=\"layout-column\">\n<div class=\"wp-block-dbec-core-layout-linked-items  wp-block-dbec-core-layout-linked-items--expanded\"><section class=\"layout-linked-items\"><div class=\"layout-linked-items__header\"><div class=\"grid\"><div class=\"column is-6-small is-3-medium\"><h2 class=\"layout-linked-items__headline\">Weitere News<\/h2><\/div><div class=\"column is-6-small is-3-medium\"><div class=\"layout-linked-items__wrapper-link layout-linked-items__wrapper-link--top\"><a class=\"layout-linked-items__link\" href=\"https:\/\/db-eco.com\/de\/news\/\" target=\"_self\" rel=\"noopener noreferrer\">Zur\u00fcck zur \u00dcbersicht<\/a><\/div><\/div><\/div><\/div><div class=\"layout-linked-items__inner\"><div class=\"related-posts\"><div class=\"related-posts__post\"><a class=\"base-card\" href=\"https:\/\/db-eco.com\/de\/aktuelles\/jahresendgruss-2025-der-db-e-c-o-group-2\/\"><figure class=\"base-card__figure\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"528\" src=\"https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-768x528.jpg\" class=\"base-card__image wp-post-image\" alt=\"Jahresendgru\u00df\" sizes=\"auto, (min-width: 1330px) calc(((1200px - 35px * 5) * (2 \/ 6)) + (35px * (2 - 1))), (min-width: 1024px) calc((((100vw - 130px) - 35px * 5) * (2 \/ 6)) + (35px * (2 - 1))), (min-width: 768px) calc((((100vw - 130px) - 35px * 5) * (3 \/ 6)) + (35px * (3 - 1))), calc(100vw - 60px)\" srcset=\"https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-768x528.jpg 768w, https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-300x206.jpg 300w, https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-1024x703.jpg 1024w, https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-1536x1055.jpg 1536w, https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-520x357.jpg 520w, https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-1280x879.jpg 1280w, https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame-1920x1319.jpg 1920w, https:\/\/db-eco.com\/wp-content\/uploads\/2025\/12\/DB_ECO_JAHRESENDFILM-2025_-Frame.jpg 1996w\" \/><\/figure><h3 class=\"base-card__title\">Jahresendgru\u00df der DB E.C.O. Group\u00a0<\/h3><div class=\"base-card__date\">Dezember 18, 2025<\/div><div class=\"base-card__copy\">Das Jahr 2025 neigt sich dem Ende zu, und wir bedanken uns bei allen Partner:innen und Kund:innen f\u00fcr ein erfolgreiches Jahr 2025.<\/div><\/a><\/div><div class=\"related-posts__post\"><a class=\"base-card\" href=\"https:\/\/db-eco.com\/de\/aktuelles\/jahresendgruss-der-db-e-c-o-group\/\"><figure class=\"base-card__figure\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"394\" src=\"https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631-768x394.png\" class=\"base-card__image wp-post-image\" alt=\"Jahresendgru\u00df 2024; Ausschnitt von Niko Warbanoff aus dem Jahresendgru\u00df\" sizes=\"auto, (min-width: 1330px) calc(((1200px - 35px * 5) * (2 \/ 6)) + (35px * (2 - 1))), (min-width: 1024px) calc((((100vw - 130px) - 35px * 5) * (2 \/ 6)) + (35px * (2 - 1))), (min-width: 768px) calc((((100vw - 130px) - 35px * 5) * (3 \/ 6)) + (35px * (3 - 1))), calc(100vw - 60px)\" srcset=\"https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631-768x394.png 768w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631-300x154.png 300w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631-1024x525.png 1024w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631-1536x788.png 1536w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631-520x267.png 520w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631-1280x657.png 1280w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/12\/screenshot-jahresendgruss-1-e1734509377631.png 1789w\" \/><div class=\"label-reference\" data-image-reference=\"DB Engineering &#038; Consulting\"><\/div><\/figure><h3 class=\"base-card__title\">Jahresendgru\u00df der DB E.C.O. Group<\/h3><div class=\"base-card__date\">Dezember 19, 2024<\/div><div class=\"base-card__copy\">Das Jahr 2024 neigt sich dem Ende zu und die DB E.C.O. Group bedankt sich bei all ihren Kunden und Partnern f\u00fcr ein gemeinsames, erfolgreiches Jahr. In unserem diesj\u00e4hrigen Jahresendgru\u00df richtet Niko Warbanoff, CEO der DB E.C.O. Group, pers\u00f6nliche Worte des Dankes an Sie \u2013 f\u00fcr Ihr Vertrauen, Ihre Unterst\u00fctzung und Ihre Zusammenarbeit. <\/div><\/a><\/div><div class=\"related-posts__post\"><a class=\"base-card\" href=\"https:\/\/db-eco.com\/de\/aktuelles\/eib-und-db-ec-eroeffnen-urban-mobility-competence-hub-in-delhi\/\"><figure class=\"base-card__figure\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-768x512.jpg\" class=\"base-card__image wp-post-image\" alt=\"Gruppenfoto der Vertreter und Vertreterinnen der DB E&amp;C und der EIB\" sizes=\"auto, (min-width: 1330px) calc(((1200px - 35px * 5) * (2 \/ 6)) + (35px * (2 - 1))), (min-width: 1024px) calc((((100vw - 130px) - 35px * 5) * (2 \/ 6)) + (35px * (2 - 1))), (min-width: 768px) calc((((100vw - 130px) - 35px * 5) * (3 \/ 6)) + (35px * (3 - 1))), calc(100vw - 60px)\" srcset=\"https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-768x512.jpg 768w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-300x200.jpg 300w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-1024x683.jpg 1024w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-1536x1024.jpg 1536w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-2048x1365.jpg 2048w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-520x347.jpg 520w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-1280x853.jpg 1280w, https:\/\/db-eco.com\/wp-content\/uploads\/2024\/10\/UMCH-Urban-Mbility-Competence-Hub-Indien-1920x1280.jpg 1920w\" \/><div class=\"label-reference\" data-image-reference=\"DB Engineering &#038; Consulting\"><\/div><\/figure><h3 class=\"base-card__title\">EIB und DB E&amp;C er\u00f6ffnen Urban Mobility Competence Hub in Indien<\/h3><div class=\"base-card__date\">Oktober 28, 2024<\/div><div class=\"base-card__copy\">Die Europ\u00e4ische Investitionsbank (EIB) hat mit der Er\u00f6ffnung des Urban Mobility Competence Hub (UMCH) in Delhi, Indien, diesen Februar einen wichtigen Schritt zur Bew\u00e4ltigung der urbanen Mobilit\u00e4tsherausforderungen Indiens unternommen. In Partnerschaft mit DB Engineering &#038; Consulting, einer Tochtergesellschaft der DB E.C.O. Group, zielt diese Initiative darauf ab, Indiens schnell wachsende St\u00e4dte bei der Entwicklung nachhaltiger und effizienter st\u00e4dtischer Verkehrssysteme zu unterst\u00fctzen. <\/div><\/a><\/div><\/div><\/div><div class=\"layout-linked-items__wrapper-link layout-linked-items__wrapper-link--bottom\"><a class=\"layout-linked-items__link\" href=\"https:\/\/db-eco.com\/de\/news\/\" target=\"_self\" rel=\"noopener noreferrer\">Zur\u00fcck zur \u00dcbersicht<\/a><\/div><\/section><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um dem wachsenden Mobilit\u00e4tsbedarf der St\u00e4dte gerecht zu werden, wurde f\u00fcr Tel Aviv ein hochmodernes MRT-System entwickelt, das sich durch Effizienz, Geschwindigkeit, Zuverl\u00e4ssigkeit und Umweltfreundlichkeit auszeichnet. Nun hat die erste dieser Linien erfolgreich den Betrieb aufgenommen. <\/p>\n","protected":false},"author":5,"featured_media":3793,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"allow-other-domains":"1"},"categories":[1,2],"tags":[357,361,360,363,362,364,358,359,356],"class_list":["post-3790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assignments","category-news","tag-israel-2","tag-light-rail-transit-2","tag-lrt","tag-mass-rapid-transit-2","tag-mrt","tag-red-line-2","tag-stadtbahn","tag-stadtbahnsystem","tag-tel-aviv-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stadtbahn Tel Aviv: Herausragende Integration der Red Line<\/title>\n<meta name=\"description\" content=\"Stadtbahn Tel Aviv: Erfahren Sie mehr dar\u00fcber, was die DB E&amp;C zu diesem System beigetragen hat, um den Verkehr in der Stadt zu verbessern.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv\" \/>\n<meta property=\"og:description\" content=\"Stadtbahn Tel Aviv: Erfahren Sie mehr dar\u00fcber, was die DB E&amp;C zu diesem System beigetragen hat, um den Verkehr in der Stadt zu verbessern.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/\" \/>\n<meta property=\"og:site_name\" content=\"DB ECO\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-20T08:08:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T23:12:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"775\" \/>\n\t<meta property=\"og:image:height\" content=\"516\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Boglarka Mihaly\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Boglarka Mihaly\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/\"},\"author\":{\"name\":\"Boglarka Mihaly\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#\\\/schema\\\/person\\\/ecd7d74fe4822613b3bb4cec3a811143\"},\"headline\":\"Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv\",\"datePublished\":\"2023-09-20T08:08:43+00:00\",\"dateModified\":\"2025-05-06T23:12:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/\"},\"wordCount\":997,\"publisher\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/db-eco.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg\",\"keywords\":[\"israel\",\"light rail transit\",\"lrt\",\"mass rapid transit\",\"mrt\",\"red line\",\"stadtbahn\",\"stadtbahnsystem\",\"tel aviv\"],\"articleSection\":[\"News\",\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/\",\"url\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/\",\"name\":\"Stadtbahn Tel Aviv: Herausragende Integration der Red Line\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/db-eco.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg\",\"datePublished\":\"2023-09-20T08:08:43+00:00\",\"dateModified\":\"2025-05-06T23:12:19+00:00\",\"description\":\"Stadtbahn Tel Aviv: Erfahren Sie mehr dar\u00fcber, was die DB E&C zu diesem System beigetragen hat, um den Verkehr in der Stadt zu verbessern.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/db-eco.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg\",\"contentUrl\":\"https:\\\/\\\/db-eco.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg\",\"width\":775,\"height\":516,\"caption\":\"Marco Cigolini \\\/ DB Engineering & Consulting\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/aktuelles\\\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/db-eco.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/db-eco.com\\\/de\\\/\",\"name\":\"DB ECO\",\"description\":\"Part of DB E.C.O. Group\",\"publisher\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/db-eco.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#organization\",\"name\":\"DB E.C.O. Group\",\"url\":\"https:\\\/\\\/db-eco.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/db-eco.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_DB-ECO-Group_310x69.jpg\",\"contentUrl\":\"https:\\\/\\\/db-eco.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Logo_DB-ECO-Group_310x69.jpg\",\"width\":310,\"height\":69,\"caption\":\"DB E.C.O. Group\"},\"image\":{\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/db-e-c-o-group\\\/\"],\"description\":\"Die DB E.C.O. Group setzt sich aus DB Engineering & Consulting, Deutsche Bahn International Operations, infraView, ESE Engineering und Software-Entwicklung, inno2grid sowie weiteren lokalen Gesellschaften, Tochterunternehmen und internationalen Beteiligungen zusammen. Das geb\u00fcndelte Fachwissen der Deutschen Bahn in den Bereichen Engineering, Consulting und Betrieb bildet die Grundlage f\u00fcr die umfassende Infrastrukturkompetenz der Gruppe. Diese Expertise ist integraler Bestandteil aller Leistungen und erm\u00f6glicht die Entwicklung innovativer und nachhaltiger L\u00f6sungen f\u00fcr die Mobilit\u00e4t der Zukunft. Seit Ende 2019 verbindet die B E.C.O. Group ihre fundierte Systemkenntnis des integrierten Schienenverkehrs mit digitalen Technologien entlang der gesamten Wertsch\u00f6pfungskette. Als Full-Service-Dienstleister mit \u00fcber 8.200 Mitarbeitenden aus 90 Nationen bietet das Unternehmen ein zukunftsorientiertes Leistungsportfolio und leistet zugleich einen aktiven Beitrag zum Umwelt- und Klimaschutz. In enger Zusammenarbeit mit Gesch\u00e4ftspartnern werden zuverl\u00e4ssige und wirtschaftliche L\u00f6sungen f\u00fcr komplexe Projekte umgesetzt.\",\"email\":\"eco-group@deutschebahn.com\",\"legalName\":\"DB Engineering & Consulting GmbH, DB E.C.O Group\",\"vatID\":\"DE 114 139 523\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"5001\",\"maxValue\":\"10000\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/db-eco.com\\\/de\\\/#\\\/schema\\\/person\\\/ecd7d74fe4822613b3bb4cec3a811143\",\"name\":\"Boglarka Mihaly\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ecaf30e13847ad668da43e783b188af9b009781e2887e15014ff8a4f82e5651?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ecaf30e13847ad668da43e783b188af9b009781e2887e15014ff8a4f82e5651?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0ecaf30e13847ad668da43e783b188af9b009781e2887e15014ff8a4f82e5651?s=96&d=mm&r=g\",\"caption\":\"Boglarka Mihaly\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stadtbahn Tel Aviv: Herausragende Integration der Red Line","description":"Stadtbahn Tel Aviv: Erfahren Sie mehr dar\u00fcber, was die DB E&C zu diesem System beigetragen hat, um den Verkehr in der Stadt zu verbessern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/","og_locale":"de_DE","og_type":"article","og_title":"Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv","og_description":"Stadtbahn Tel Aviv: Erfahren Sie mehr dar\u00fcber, was die DB E&C zu diesem System beigetragen hat, um den Verkehr in der Stadt zu verbessern.","og_url":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/","og_site_name":"DB ECO","article_published_time":"2023-09-20T08:08:43+00:00","article_modified_time":"2025-05-06T23:12:19+00:00","og_image":[{"width":775,"height":516,"url":"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg","type":"image\/jpeg"}],"author":"Boglarka Mihaly","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Boglarka Mihaly","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/#article","isPartOf":{"@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/"},"author":{"name":"Boglarka Mihaly","@id":"https:\/\/db-eco.com\/de\/#\/schema\/person\/ecd7d74fe4822613b3bb4cec3a811143"},"headline":"Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv","datePublished":"2023-09-20T08:08:43+00:00","dateModified":"2025-05-06T23:12:19+00:00","mainEntityOfPage":{"@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/"},"wordCount":997,"publisher":{"@id":"https:\/\/db-eco.com\/de\/#organization"},"image":{"@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/#primaryimage"},"thumbnailUrl":"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg","keywords":["israel","light rail transit","lrt","mass rapid transit","mrt","red line","stadtbahn","stadtbahnsystem","tel aviv"],"articleSection":["News","News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/","url":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/","name":"Stadtbahn Tel Aviv: Herausragende Integration der Red Line","isPartOf":{"@id":"https:\/\/db-eco.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/#primaryimage"},"image":{"@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/#primaryimage"},"thumbnailUrl":"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg","datePublished":"2023-09-20T08:08:43+00:00","dateModified":"2025-05-06T23:12:19+00:00","description":"Stadtbahn Tel Aviv: Erfahren Sie mehr dar\u00fcber, was die DB E&C zu diesem System beigetragen hat, um den Verkehr in der Stadt zu verbessern.","breadcrumb":{"@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/#primaryimage","url":"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg","contentUrl":"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg","width":775,"height":516,"caption":"Marco Cigolini \/ DB Engineering & Consulting"},{"@type":"BreadcrumbList","@id":"https:\/\/db-eco.com\/de\/aktuelles\/herausragende-pionierleistung-die-integration-des-stadtbahnsystems-der-red-line-von-tel-aviv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/db-eco.com\/de\/"},{"@type":"ListItem","position":2,"name":"Herausragende Pionierleistung: die Integration des Stadtbahnsystems der Red Line von Tel Aviv"}]},{"@type":"WebSite","@id":"https:\/\/db-eco.com\/de\/#website","url":"https:\/\/db-eco.com\/de\/","name":"DB ECO","description":"Part of DB E.C.O. Group","publisher":{"@id":"https:\/\/db-eco.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/db-eco.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/db-eco.com\/de\/#organization","name":"DB E.C.O. Group","url":"https:\/\/db-eco.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/db-eco.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/db-eco.com\/wp-content\/uploads\/2022\/10\/Logo_DB-ECO-Group_310x69.jpg","contentUrl":"https:\/\/db-eco.com\/wp-content\/uploads\/2022\/10\/Logo_DB-ECO-Group_310x69.jpg","width":310,"height":69,"caption":"DB E.C.O. Group"},"image":{"@id":"https:\/\/db-eco.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/db-e-c-o-group\/"],"description":"Die DB E.C.O. Group setzt sich aus DB Engineering & Consulting, Deutsche Bahn International Operations, infraView, ESE Engineering und Software-Entwicklung, inno2grid sowie weiteren lokalen Gesellschaften, Tochterunternehmen und internationalen Beteiligungen zusammen. Das geb\u00fcndelte Fachwissen der Deutschen Bahn in den Bereichen Engineering, Consulting und Betrieb bildet die Grundlage f\u00fcr die umfassende Infrastrukturkompetenz der Gruppe. Diese Expertise ist integraler Bestandteil aller Leistungen und erm\u00f6glicht die Entwicklung innovativer und nachhaltiger L\u00f6sungen f\u00fcr die Mobilit\u00e4t der Zukunft. Seit Ende 2019 verbindet die B E.C.O. Group ihre fundierte Systemkenntnis des integrierten Schienenverkehrs mit digitalen Technologien entlang der gesamten Wertsch\u00f6pfungskette. Als Full-Service-Dienstleister mit \u00fcber 8.200 Mitarbeitenden aus 90 Nationen bietet das Unternehmen ein zukunftsorientiertes Leistungsportfolio und leistet zugleich einen aktiven Beitrag zum Umwelt- und Klimaschutz. In enger Zusammenarbeit mit Gesch\u00e4ftspartnern werden zuverl\u00e4ssige und wirtschaftliche L\u00f6sungen f\u00fcr komplexe Projekte umgesetzt.","email":"eco-group@deutschebahn.com","legalName":"DB Engineering & Consulting GmbH, DB E.C.O Group","vatID":"DE 114 139 523","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"5001","maxValue":"10000"}},{"@type":"Person","@id":"https:\/\/db-eco.com\/de\/#\/schema\/person\/ecd7d74fe4822613b3bb4cec3a811143","name":"Boglarka Mihaly","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0ecaf30e13847ad668da43e783b188af9b009781e2887e15014ff8a4f82e5651?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0ecaf30e13847ad668da43e783b188af9b009781e2887e15014ff8a4f82e5651?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0ecaf30e13847ad668da43e783b188af9b009781e2887e15014ff8a4f82e5651?s=96&d=mm&r=g","caption":"Boglarka Mihaly"}}]}},"dbec_featured_media":{"source_url":"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-300x200.jpg","source_set":"https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-300x200.jpg 300w, https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-768x511.jpg 768w, https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line-520x346.jpg 520w, https:\/\/db-eco.com\/wp-content\/uploads\/2023\/09\/Stadtbahn-Tel-Aviv-Betriebsbeginn-der-Red-Line.jpg 775w","caption":"Marco Cigolini \/ DB Engineering & Consulting","alt":"Stadtbahn Tel Aviv w\u00e4hrend der Fahrt durch die Stadt"},"post_views":3821,"_links":{"self":[{"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/posts\/3790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/comments?post=3790"}],"version-history":[{"count":16,"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/posts\/3790\/revisions"}],"predecessor-version":[{"id":7695,"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/posts\/3790\/revisions\/7695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/media\/3793"}],"wp:attachment":[{"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/media?parent=3790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/categories?post=3790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/db-eco.com\/de\/wp-json\/wp\/v2\/tags?post=3790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}